{"id":824,"date":"2025-06-12T11:17:29","date_gmt":"2025-06-12T09:17:29","guid":{"rendered":"https:\/\/appli-voyages.com\/moulin-neuf\/?post_type=tourisme&#038;p=824"},"modified":"2025-06-12T11:17:30","modified_gmt":"2025-06-12T09:17:30","slug":"la-base-de-loisirs-moulin-neuf-aventure","status":"publish","type":"tourisme","link":"https:\/\/appli-voyages.com\/moulin-neuf\/tourisme\/la-base-de-loisirs-moulin-neuf-aventure\/","title":{"rendered":"La base de loisirs Moulin Neuf Aventure"},"content":{"rendered":"\n<p>\u00c0 deux pas du <strong>Domaine du Moulin Neuf<\/strong> (10 minutes \u00e0 pied), offrez-vous un moment d\u2019\u00e9vasion \u00e0 la <strong>base de loisirs Moulin Neuf Aventure<\/strong>. Nich\u00e9 au bord de l&rsquo;\u00e9tang, ce site unique propose une multitude d&rsquo;activit\u00e9s pour petits et grands : p\u00e9dalo, paddle, cano\u00eb, rosalie, v\u00e9lo, kart \u00e0 p\u00e9dales\u2026 <\/p>\n\n\n\n<p>Les plus t\u00e9m\u00e9raires pourront s&rsquo;\u00e9lancer depuis la tyrolienne g\u00e9ante pour une descente grisante au-dessus de l&rsquo;eau, tandis que les aventuriers en herbe partiront \u00e0 l\u2019assaut du parcours filets suspendu dans les arbres. Pour un moment unique, laissez-vous tenter par l&rsquo;ap\u00e9ro p\u00e9dalo : savourez un panier de produits locaux en flottant paisiblement sur l&rsquo;\u00e9tang.<\/p>\n\n\n\n<p>Que vous soyez en qu\u00eate de d\u00e9tente ou de sensations, <strong>Moulin Neuf Aventure<\/strong> est l&rsquo;escapade id\u00e9ale pour rythmer votre s\u00e9jour au Domaine.<\/p>\n\n\n\n<p><em>Cr\u00e9dit Photo : Loisirs_nautiques_Moulin_Neuf Aventure \u00a9Loic Kersuzan &#8211; Morbihan Tourisme<\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"featured_media":825,"parent":0,"menu_order":3,"template":"","class_list":["post-824","tourisme","type-tourisme","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/appli-voyages.com\/moulin-neuf\/wp-json\/wp\/v2\/tourisme\/824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/appli-voyages.com\/moulin-neuf\/wp-json\/wp\/v2\/tourisme"}],"about":[{"href":"https:\/\/appli-voyages.com\/moulin-neuf\/wp-json\/wp\/v2\/types\/tourisme"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/appli-voyages.com\/moulin-neuf\/wp-json\/wp\/v2\/media\/825"}],"wp:attachment":[{"href":"https:\/\/appli-voyages.com\/moulin-neuf\/wp-json\/wp\/v2\/media?parent=824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}