{"id":165,"date":"2024-02-21T14:01:13","date_gmt":"2024-02-21T13:01:13","guid":{"rendered":"http:\/\/room-directory.local\/?post_type=tourisme&#038;p=165"},"modified":"2025-06-12T11:23:54","modified_gmt":"2025-06-12T09:23:54","slug":"rochefort-en-terre","status":"publish","type":"tourisme","link":"https:\/\/appli-voyages.com\/moulin-neuf\/tourisme\/rochefort-en-terre\/","title":{"rendered":"Rochefort-en-Terre"},"content":{"rendered":"\n<p>C\u2019est un plaisir de fl\u00e2ner dans cette adorable \u00ab petite cit\u00e9 de caract\u00e8re \u00bb, b\u00e2tie sur un \u00e9peron rocheux et renomm\u00e9e pour ses logis du XVIe et XVIIe si\u00e8cle ! Avec ses ruelles de charme, ses maisons \u00e0 pans de bois arborant des balcons fleuris, ses boutiques artisanales, son ch\u00e2teau, ainsi que l\u2019\u00e9glise Notre-Dame de la Tronchaye, elle ne pourra que vous s\u00e9duire.<\/p>\n\n\n\n<p><br>Lab\u00e9lis\u00e9e Les Plus Beaux Villages de France\u00ae , \u00ab Ville Fleurie \u00bb, \u00ab Petite Cit\u00e9 de caract\u00e8re \u00bb, \u00ab Village pr\u00e9f\u00e9r\u00e9 des Fran\u00e7ais 2016 \u00bb et \u00ab Merveilleux Village de No\u00ebl 2017 \u00bb, Rochefort-en-Terre est un haut-lieu d\u2019artisanat et d\u2019art avec un juste \u00e9quilibre entre authenticit\u00e9 et valorisation touristique.<\/p>\n","protected":false},"featured_media":360,"parent":0,"menu_order":2,"template":"","class_list":["post-165","tourisme","type-tourisme","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/appli-voyages.com\/moulin-neuf\/wp-json\/wp\/v2\/tourisme\/165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/appli-voyages.com\/moulin-neuf\/wp-json\/wp\/v2\/tourisme"}],"about":[{"href":"https:\/\/appli-voyages.com\/moulin-neuf\/wp-json\/wp\/v2\/types\/tourisme"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/appli-voyages.com\/moulin-neuf\/wp-json\/wp\/v2\/media\/360"}],"wp:attachment":[{"href":"https:\/\/appli-voyages.com\/moulin-neuf\/wp-json\/wp\/v2\/media?parent=165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}